{"id":53407,"date":"2024-06-11T14:55:28","date_gmt":"2024-06-11T12:55:28","guid":{"rendered":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/"},"modified":"2026-02-21T09:10:23","modified_gmt":"2026-02-21T08:10:23","slug":"morbus-meniere","status":"publish","type":"complaint","link":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/","title":{"rendered":"M\u00e9ni\u00e8re-Krankheit"},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[]},"complaint_tag":[],"complaint_body_part":[],"complaint_age_group":[],"complaint_category":[],"class_list":["post-53407","complaint","type-complaint","status-publish","hentry"],"acf":{"short_description_title":"","short_description_content":"","tabs":[{"title":"Was ist die M\u00e9ni\u00e8re-Krankheit?","content":"<p>Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Infolgedessen werden Sie Symptome bei Anf\u00e4llen entwickeln. Das Innenohr besteht aus drei R\u00e4umen, die mit Fl\u00fcssigkeiten gef\u00fcllt sind. Im mittleren Raum kann sich zu viel Fl\u00fcssigkeit bilden, was den Druck im Ohr erh\u00f6ht. Dann sp\u00fcrst du ein Druckgef\u00fchl im Ohr. Die Membran zwischen den Zwischenr\u00e4umen kann sich durch den zunehmenden Druck dehnen und schlie\u00dflich rei\u00dfen. Dadurch k\u00f6nnen sich die verschiedenen Fl\u00fcssigkeiten in den R\u00e4umen vermischen und das Organ des Gleichgewichts und des H\u00f6rens werden verwechselt. Dies f\u00fchrt zu einem M\u00e9ni\u00e8re-Angriff.<\/p>\n"},{"title":"Welche Symptome habe ich bei der M\u00e9ni\u00e8re-Krankheit?","content":"<p>Bei Morbus M\u00e9ni\u00e8re bekommt man schwere <a href=\"https:\/\/multisite.mindd.dev\/de-de\/klacht\/draaiduizeligheid\/\">Schwindelattacken<\/a> . Bei Schwindel hat man das Gef\u00fchl, dass man selbst oder alles um einen herum sich dreht.\u00a0 Oft gibt es neben dem Schwindel auch andere Beschwerden. Sie k\u00f6nnten au\u00dferdem unter folgendem leiden:<\/p>\n<ul>\n<li>\u00dcbelkeit.<\/li>\n<li>Angst.<\/li>\n<li><a href=\"https:\/\/multisite.mindd.dev\/de-de\/klacht\/overgeven\/\">Erbrechen.<\/a><\/li>\n<li>Ein Klingeln in deinen Ohren.<\/li>\n<li>Migr\u00e4ne.<\/li>\n<li>Der Schwindel tritt in Anf\u00e4llen auf, die zwanzig Minuten bis zw\u00f6lf Stunden andauern k\u00f6nnen.<\/li>\n<\/ul>\n"},{"title":"Was kann ich selbst mit der M\u00e9ni\u00e8re-Krankheit tun?","content":"<p>Ein Schwindelanfall verschwindet von selbst, aber Sie k\u00f6nnen Folgendes tun, um die Symptome zu lindern:<\/p>\n<ul>\n<li>Schlaf auf zwei Kissen.<\/li>\n<li>Steh nicht zu schnell auf.<\/li>\n<li>Versuche, dich nicht zu b\u00fccken, sondern zum Beispiel in die Hocke, um etwas hochzuheben.<\/li>\n<li>Mach weiter mit den Dingen, die du immer getan hast. Nehmen Sie sich bei Bedarf extra aus.<\/li>\n<li>Wenn es dich sehr st\u00f6rt, kannst du dich hinlegen oder sitzen.<\/li>\n<\/ul>\n"},{"title":"Wann sollte ich wegen Morbus M\u00e9ni\u00e8re einen Arzt aufsuchen?","content":"<p>Kontaktieren Sie Ihren Arzt, wenn:<\/p>\n<ul>\n<li>Sie leiden an Symptomen, die mit der M\u00e9ni\u00e8re-Krankheit \u00fcbereinstimmen.<\/li>\n<li>Man ist pl\u00f6tzlich taub oder leicht taub.<\/li>\n<li>Sie haben schwerwiegendere Symptome als sonst aufgrund eines Anfalls der M\u00e9ni\u00e8re-Krankheit.<\/li>\n<li>Sie leiden regelm\u00e4\u00dfig unter wiederkehrenden Beschwerden.<\/li>\n<\/ul>\n"}],"original_post_id":"7_646","disable_sync":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9ni\u00e8re-Krankheit - multisite-base-de-de<\/title>\n<meta name=\"description\" content=\"Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Lesen Sie hier, wie Sie Symptome lindern k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9ni\u00e8re-Krankheit - multisite-base-de-de\" \/>\n<meta property=\"og:description\" content=\"Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Lesen Sie hier, wie Sie Symptome lindern k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/\" \/>\n<meta property=\"og:site_name\" content=\"multisite-base-de-de\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-21T08:10:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/gesundheitsbeschwerden\\\/morbus-meniere\\\/\",\"url\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/gesundheitsbeschwerden\\\/morbus-meniere\\\/\",\"name\":\"M\u00e9ni\u00e8re-Krankheit - multisite-base-de-de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/#website\"},\"datePublished\":\"2024-06-11T12:55:28+00:00\",\"dateModified\":\"2026-02-21T08:10:23+00:00\",\"description\":\"Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Lesen Sie hier, wie Sie Symptome lindern k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/gesundheitsbeschwerden\\\/morbus-meniere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/gesundheitsbeschwerden\\\/morbus-meniere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/gesundheitsbeschwerden\\\/morbus-meniere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Complaints\",\"item\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/gesundheitsbeschwerden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e9ni\u00e8re-Krankheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/\",\"name\":\"multisite-base-de-de\",\"description\":\"Development site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multisite.mindd.dev\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9ni\u00e8re-Krankheit - multisite-base-de-de","description":"Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Lesen Sie hier, wie Sie Symptome lindern k\u00f6nnen.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"M\u00e9ni\u00e8re-Krankheit - multisite-base-de-de","og_description":"Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Lesen Sie hier, wie Sie Symptome lindern k\u00f6nnen.","og_url":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/","og_site_name":"multisite-base-de-de","article_modified_time":"2026-02-21T08:10:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/","url":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/","name":"M\u00e9ni\u00e8re-Krankheit - multisite-base-de-de","isPartOf":{"@id":"https:\/\/multisite.mindd.dev\/de-de\/#website"},"datePublished":"2024-06-11T12:55:28+00:00","dateModified":"2026-02-21T08:10:23+00:00","description":"Die M\u00e9ni\u00e8re-Krankheit f\u00fchrt dazu, dass das Innenohr nicht richtig funktioniert. Lesen Sie hier, wie Sie Symptome lindern k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/morbus-meniere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multisite.mindd.dev\/de-de\/"},{"@type":"ListItem","position":2,"name":"Complaints","item":"https:\/\/multisite.mindd.dev\/de-de\/gesundheitsbeschwerden\/"},{"@type":"ListItem","position":3,"name":"M\u00e9ni\u00e8re-Krankheit"}]},{"@type":"WebSite","@id":"https:\/\/multisite.mindd.dev\/de-de\/#website","url":"https:\/\/multisite.mindd.dev\/de-de\/","name":"multisite-base-de-de","description":"Development site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multisite.mindd.dev\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/complaint\/53407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/complaint"}],"about":[{"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/types\/complaint"}],"wp:attachment":[{"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/media?parent=53407"}],"wp:term":[{"taxonomy":"complaint_tag","embeddable":true,"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/complaint_tag?post=53407"},{"taxonomy":"complaint_body_part","embeddable":true,"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/complaint_body_part?post=53407"},{"taxonomy":"complaint_age_group","embeddable":true,"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/complaint_age_group?post=53407"},{"taxonomy":"complaint_category","embeddable":true,"href":"https:\/\/multisite.mindd.dev\/de-de\/wp-json\/wp\/v2\/complaint_category?post=53407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}