{"id":49153,"date":"2023-04-21T14:50:53","date_gmt":"2023-04-21T12:50:53","guid":{"rendered":"https:\/\/multisite.mindd.dev\/?page_id=49153"},"modified":"2023-04-21T14:50:54","modified_gmt":"2023-04-21T12:50:54","slug":"heeft-u-een-compliment","status":"publish","type":"page","link":"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/","title":{"rendered":"Heeft u een compliment?"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">Bent u tevreden over uw bezoek aan de huisartsenpost? Dan horen wij dat graag. Met het formulier kunt u ons dit laten weten. U krijgt automatisch een kopie van het bericht toegestuurd. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bent u tevreden over uw bezoek aan de huisartsenpost? Dan horen wij dat graag. Met het formulier kunt u ons dit laten weten. U krijgt automatisch een kopie van het bericht toegestuurd.<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"class_list":["post-49153","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heeft u een compliment? - multisite-base-da-dk<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heeft u een compliment? - multisite-base-da-dk\" \/>\n<meta property=\"og:description\" content=\"Bent u tevreden over uw bezoek aan de huisartsenpost? Dan horen wij dat graag. Met het formulier kunt u ons dit laten weten. U krijgt automatisch een kopie van het bericht toegestuurd.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/\" \/>\n<meta property=\"og:site_name\" content=\"multisite-base-da-dk\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-21T12:50:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/heeft-u-een-compliment\\\/\",\"url\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/heeft-u-een-compliment\\\/\",\"name\":\"Heeft u een compliment? - multisite-base-da-dk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/#website\"},\"datePublished\":\"2023-04-21T12:50:53+00:00\",\"dateModified\":\"2023-04-21T12:50:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/heeft-u-een-compliment\\\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/heeft-u-een-compliment\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/heeft-u-een-compliment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heeft u een compliment?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/#website\",\"url\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/\",\"name\":\"multisite-base-da-dk\",\"description\":\"Development site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multisite.mindd.dev\\\/da-dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heeft u een compliment? - multisite-base-da-dk","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"da_DK","og_type":"article","og_title":"Heeft u een compliment? - multisite-base-da-dk","og_description":"Bent u tevreden over uw bezoek aan de huisartsenpost? Dan horen wij dat graag. Met het formulier kunt u ons dit laten weten. U krijgt automatisch een kopie van het bericht toegestuurd.","og_url":"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/","og_site_name":"multisite-base-da-dk","article_modified_time":"2023-04-21T12:50:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimeret l\u00e6setid":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/","url":"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/","name":"Heeft u een compliment? - multisite-base-da-dk","isPartOf":{"@id":"https:\/\/multisite.mindd.dev\/da-dk\/#website"},"datePublished":"2023-04-21T12:50:53+00:00","dateModified":"2023-04-21T12:50:54+00:00","breadcrumb":{"@id":"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/multisite.mindd.dev\/da-dk\/heeft-u-een-compliment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multisite.mindd.dev\/da-dk\/"},{"@type":"ListItem","position":2,"name":"Heeft u een compliment?"}]},{"@type":"WebSite","@id":"https:\/\/multisite.mindd.dev\/da-dk\/#website","url":"https:\/\/multisite.mindd.dev\/da-dk\/","name":"multisite-base-da-dk","description":"Development site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multisite.mindd.dev\/da-dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"}]}},"_links":{"self":[{"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/pages\/49153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/comments?post=49153"}],"version-history":[{"count":0,"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/pages\/49153\/revisions"}],"wp:attachment":[{"href":"https:\/\/multisite.mindd.dev\/da-dk\/wp-json\/wp\/v2\/media?parent=49153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}