{"id":49157,"date":"2023-04-21T14:51:36","date_gmt":"2023-04-21T12:51:36","guid":{"rendered":"https:\/\/multisite.mindd.dev\/?page_id=49157"},"modified":"2023-04-21T14:51:38","modified_gmt":"2023-04-21T12:51:38","slug":"huisregels-op-de-huisartsenpost","status":"publish","type":"page","link":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/","title":{"rendered":"Huisregels op de huisartsenpost"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\"><strong>Spoed gaat altijd voor<\/strong><br>Wij proberen iedereen zo snel mogelijk te helpen, maar de ernst van de klacht is leidend. Het kan daarom voorkomen dat een pati\u00ebnt die zich later heeft gemeld, eerder wordt geholpen. Wij vragen hiervoor uw begrip. Als u een half uur nadat u uw afspraak had nog niet geholpen bent, wilt u zich dan melden aan de balie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Op de posten gaan we respectvol met elkaar om<\/strong><br>Wij respecteren iedereen, ongeacht afkomst, geloof, kleding, geslacht, leeftijd, uiterlijk of seksuele geaardheid. Als u van mening bent dat u niet respectvol bejegend wordt, kunt u dat het beste meteen op de huisartsenpost met ons bespreken. Wij accepteren echter geen verbaal of fysiek geweld, diefstal, wapens en drugs, alcoholgebruik of seksuele intimidatie.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wat als u de huisregels niet respecteert<\/strong><br>U krijgt eerst een waarschuwing. Bij herhaling van ongewenst gedrag doen wij aangifte bij de politie en wordt u de toegang tot de huisartenpost ontzegd. Bij bedreiging, vernieling en handtastelijkheden schakelen we altijd de politie in.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spoed gaat altijd voorWij proberen iedereen zo snel mogelijk te helpen, maar de ernst van de klacht is leidend. Het kan daarom voorkomen dat een pati\u00ebnt die zich later heeft gemeld, eerder wordt geholpen. Wij vragen hiervoor uw begrip. Als u een half uur nadat u uw afspraak had nog niet geholpen bent, wilt u [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"class_list":["post-49157","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Huisregels op de huisartsenpost - This is just a test<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huisregels op de huisartsenpost - This is just a test\" \/>\n<meta property=\"og:description\" content=\"Spoed gaat altijd voorWij proberen iedereen zo snel mogelijk te helpen, maar de ernst van de klacht is leidend. Het kan daarom voorkomen dat een pati\u00ebnt die zich later heeft gemeld, eerder wordt geholpen. Wij vragen hiervoor uw begrip. Als u een half uur nadat u uw afspraak had nog niet geholpen bent, wilt u [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/\" \/>\n<meta property=\"og:site_name\" content=\"This is just a test\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-21T12:51:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/huisregels-op-de-huisartsenpost\\\/\",\"url\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/huisregels-op-de-huisartsenpost\\\/\",\"name\":\"Huisregels op de huisartsenpost - This is just a test\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/#website\"},\"datePublished\":\"2023-04-21T12:51:36+00:00\",\"dateModified\":\"2023-04-21T12:51:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/huisregels-op-de-huisartsenpost\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/huisregels-op-de-huisartsenpost\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/huisregels-op-de-huisartsenpost\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Huisregels op de huisartsenpost\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/#website\",\"url\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/\",\"name\":\"This is just a test\",\"description\":\"Development site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multisite.mindd.dev\\\/autotranslate-batch-test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Huisregels op de huisartsenpost - This is just a test","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Huisregels op de huisartsenpost - This is just a test","og_description":"Spoed gaat altijd voorWij proberen iedereen zo snel mogelijk te helpen, maar de ernst van de klacht is leidend. Het kan daarom voorkomen dat een pati\u00ebnt die zich later heeft gemeld, eerder wordt geholpen. Wij vragen hiervoor uw begrip. Als u een half uur nadat u uw afspraak had nog niet geholpen bent, wilt u [&hellip;]","og_url":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/","og_site_name":"This is just a test","article_modified_time":"2023-04-21T12:51:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/","url":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/","name":"Huisregels op de huisartsenpost - This is just a test","isPartOf":{"@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/#website"},"datePublished":"2023-04-21T12:51:36+00:00","dateModified":"2023-04-21T12:51:38+00:00","breadcrumb":{"@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/huisregels-op-de-huisartsenpost\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/"},{"@type":"ListItem","position":2,"name":"Huisregels op de huisartsenpost"}]},{"@type":"WebSite","@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/#website","url":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/","name":"This is just a test","description":"Development site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/pages\/49157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/comments?post=49157"}],"version-history":[{"count":0,"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/pages\/49157\/revisions"}],"wp:attachment":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/media?parent=49157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}