{"id":54104,"date":"2023-07-19T13:58:27","date_gmt":"2023-07-19T11:58:27","guid":{"rendered":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/veelgestelde-vragen\/wie-betaalt-de-kosten-2\/"},"modified":"2024-03-20T11:26:55","modified_gmt":"2024-03-20T10:26:55","slug":"wie-betaalt-de-kosten-2","status":"publish","type":"faq","link":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/","title":{"rendered":"Wie betaalt de kosten?"},"content":{"rendered":"\n<p>U bent verplicht zelf een zorgverzekering af te sluiten. Pati\u00ebnten die niet kunnen aantonen dat zij verzekerd zijn dienen direct op de huisartsenpost te betalen. Deze pati\u00ebnten kunnen de kosten achteraf declareren als zij hiervoor verzekerd zijn. Dit geldt ook voor alle buitenlandse toeristen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>U bent verplicht zelf een zorgverzekering af te sluiten. Pati\u00ebnten die niet kunnen aantonen dat zij verzekerd zijn dienen direct op de huisartsenpost te betalen. Deze pati\u00ebnten kunnen de kosten achteraf declareren als zij hiervoor verzekerd zijn. Dit geldt ook voor alle buitenlandse toeristen.<\/p>\n","protected":false},"menu_order":0,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"question_type":[],"class_list":["post-54104","faq","type-faq","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wie betaalt de kosten? - This is just a test<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie betaalt de kosten? - This is just a test\" \/>\n<meta property=\"og:description\" content=\"U bent verplicht zelf een zorgverzekering af te sluiten. Pati\u00ebnten die niet kunnen aantonen dat zij verzekerd zijn dienen direct op de huisartsenpost te betalen. Deze pati\u00ebnten kunnen de kosten achteraf declareren als zij hiervoor verzekerd zijn. Dit geldt ook voor alle buitenlandse toeristen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/\" \/>\n<meta property=\"og:site_name\" content=\"This is just a test\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T10:26:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/\",\"url\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/\",\"name\":\"Wie betaalt de kosten? - This is just a test\",\"isPartOf\":{\"@id\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/#website\"},\"datePublished\":\"2023-07-19T11:58:27+00:00\",\"dateModified\":\"2024-03-20T10:26:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQS\",\"item\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wie betaalt de kosten?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/#website\",\"url\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/\",\"name\":\"This is just a test\",\"description\":\"Development site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie betaalt de kosten? - This is just a test","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Wie betaalt de kosten? - This is just a test","og_description":"U bent verplicht zelf een zorgverzekering af te sluiten. Pati\u00ebnten die niet kunnen aantonen dat zij verzekerd zijn dienen direct op de huisartsenpost te betalen. Deze pati\u00ebnten kunnen de kosten achteraf declareren als zij hiervoor verzekerd zijn. Dit geldt ook voor alle buitenlandse toeristen.","og_url":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/","og_site_name":"This is just a test","article_modified_time":"2024-03-20T10:26:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/","url":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/","name":"Wie betaalt de kosten? - This is just a test","isPartOf":{"@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/#website"},"datePublished":"2023-07-19T11:58:27+00:00","dateModified":"2024-03-20T10:26:55+00:00","breadcrumb":{"@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/wie-betaalt-de-kosten-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/"},{"@type":"ListItem","position":2,"name":"FAQS","item":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/haeufig-gestellte-fragen\/"},{"@type":"ListItem","position":3,"name":"Wie betaalt de kosten?"}]},{"@type":"WebSite","@id":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/#website","url":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/","name":"This is just a test","description":"Development site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/faq\/54104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/types\/faq"}],"version-history":[{"count":1,"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/faq\/54104\/revisions"}],"predecessor-version":[{"id":54105,"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/faq\/54104\/revisions\/54105"}],"wp:attachment":[{"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/media?parent=54104"}],"wp:term":[{"taxonomy":"question_type","embeddable":true,"href":"https:\/\/multisite.mindd.dev\/autotranslate-batch-test\/wp-json\/wp\/v2\/question_type?post=54104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}